{"id":7466,"date":"2026-02-24T16:28:44","date_gmt":"2026-02-24T16:28:44","guid":{"rendered":"https:\/\/www.sbhny.org\/?post_type=tribe_events&#038;p=7466"},"modified":"2026-02-24T16:58:36","modified_gmt":"2026-02-24T16:58:36","slug":"community-class-one-pot-meals-comidas-de-una-olla-10","status":"publish","type":"tribe_events","link":"https:\/\/www.sbhny.org\/fr\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/","title":{"rendered":"Classe communautaire : Repas \u00e0 un pot \/ Comidas de una olla"},"content":{"rendered":"<p>La vaisselle vous d\u00e9go\u00fbte ? Alors un repas en une seule marmite est parfait pour vous ! Dans ce cours, nous vous montrerons une vari\u00e9t\u00e9 de recettes qui ne n\u00e9cessitent qu'une seule marmite ou une seule po\u00eale.<\/p>\n<p>NIVEAU DE CLASSE : INTERM\u00c9DIAIRE<\/p>\n<p>&nbsp;<\/p>\n<p>Tu d\u00e9testes faire la vaisselle ? Alors un repas en une seule marmite est parfait pour toi ! Dans ce cours, nous te montrerons une vari\u00e9t\u00e9 de recettes qui ne n\u00e9cessitent qu'une seule casserole ou po\u00eale.<\/p>\n<p>NIVEAU DE CLASSE : INTERM\u00c9DIAIRE<\/p>","protected":false},"excerpt":{"rendered":"<p>Hate washing dishes? Then a one-pot meal is perfect for you! In this class, we\u2019ll show you a variety of recipes that only need one pot or one pan. CLASS [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_eb_attr":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"TEC\\Tickets\\Commerce\\Module","_tribe_ticket_capacity":"10","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"1","_tribe_ticket_global_stock_level":"10","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[{\"id\":7467,\"type\":\"default\",\"title\":\"Community Class: One-Pot Meals \\\/ Comidas de una olla\",\"description\":\"\",\"capacityType\":\"global\",\"price\":\"5\",\"capacity\":10,\"available\":10,\"sharedCapacity\":10,\"sold\":0,\"shareSold\":0,\"isShared\":true,\"currencyDecimalPoint\":\".\",\"currencyNumberOfDecimals\":2,\"currencyPosition\":\"prefix\",\"currencySymbol\":\"$\",\"currencyThousandsSep\":\",\"}]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[138],"class_list":["post-7466","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-community-classes","cat_community-classes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Community Class: One-Pot Meals \/ Comidas de una olla - SBH Health System<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sbhny.org\/fr\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Community Class: One-Pot Meals \/ Comidas de una olla - SBH Health System\" \/>\n<meta property=\"og:description\" content=\"Hate washing dishes? Then a one-pot meal is perfect for you! In this class, we\u2019ll show you a variety of recipes that only need one pot or one pan. CLASS [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sbhny.org\/fr\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/\" \/>\n<meta property=\"og:site_name\" content=\"SBH Health System\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SBHBronx\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T16:58:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sbhbronx\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sbhny.org\\\/class\\\/community-class-one-pot-meals-comidas-de-una-olla-10\\\/\",\"url\":\"https:\\\/\\\/www.sbhny.org\\\/class\\\/community-class-one-pot-meals-comidas-de-una-olla-10\\\/\",\"name\":\"Community Class: One-Pot Meals \\\/ Comidas de una olla - SBH Health System\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sbhny.org\\\/#website\"},\"datePublished\":\"2026-02-24T16:28:44+00:00\",\"dateModified\":\"2026-02-24T16:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sbhny.org\\\/class\\\/community-class-one-pot-meals-comidas-de-una-olla-10\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sbhny.org\\\/class\\\/community-class-one-pot-meals-comidas-de-una-olla-10\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sbhny.org\\\/class\\\/community-class-one-pot-meals-comidas-de-una-olla-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sbhny.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.sbhny.org\\\/classes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Community Class: One-Pot Meals \\\/ Comidas de una olla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sbhny.org\\\/#website\",\"url\":\"https:\\\/\\\/www.sbhny.org\\\/\",\"name\":\"SBH Health System\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sbhny.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Community Class: One-Pot Meals \/ Comidas de una olla - SBH Health System","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sbhny.org\/fr\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/","og_locale":"fr_FR","og_type":"article","og_title":"Community Class: One-Pot Meals \/ Comidas de una olla - SBH Health System","og_description":"Hate washing dishes? Then a one-pot meal is perfect for you! In this class, we\u2019ll show you a variety of recipes that only need one pot or one pan. CLASS [&hellip;]","og_url":"https:\/\/www.sbhny.org\/fr\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/","og_site_name":"SBH Health System","article_publisher":"https:\/\/www.facebook.com\/SBHBronx\/","article_modified_time":"2026-02-24T16:58:36+00:00","twitter_card":"summary_large_image","twitter_site":"@sbhbronx","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sbhny.org\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/","url":"https:\/\/www.sbhny.org\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/","name":"Community Class: One-Pot Meals \/ Comidas de una olla - SBH Health System","isPartOf":{"@id":"https:\/\/www.sbhny.org\/#website"},"datePublished":"2026-02-24T16:28:44+00:00","dateModified":"2026-02-24T16:58:36+00:00","breadcrumb":{"@id":"https:\/\/www.sbhny.org\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sbhny.org\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sbhny.org\/class\/community-class-one-pot-meals-comidas-de-una-olla-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sbhny.org\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.sbhny.org\/classes\/"},{"@type":"ListItem","position":3,"name":"Community Class: One-Pot Meals \/ Comidas de una olla"}]},{"@type":"WebSite","@id":"https:\/\/www.sbhny.org\/#website","url":"https:\/\/www.sbhny.org\/","name":"Syst\u00e8me de sant\u00e9 SBH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sbhny.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"ticketed":["tc"],"_links":{"self":[{"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/tribe_events\/7466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":0,"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/tribe_events\/7466\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/media?parent=7466"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/tags?post=7466"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.sbhny.org\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=7466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}